{"id":52658,"date":"2026-09-02T22:06:18","date_gmt":"2026-09-02T20:06:18","guid":{"rendered":"https:\/\/fiajewels.it\/?post_type=product&#038;p=52658"},"modified":"2026-09-02T22:25:31","modified_gmt":"2026-09-02T20:25:31","slug":"collana-multifilo-in-perle-ceramica-di-caltagirone-radice-di-rubino","status":"publish","type":"product","link":"https:\/\/fiajewels.it\/en\/product\/collana-multifilo-in-perle-ceramica-di-caltagirone-radice-di-rubino\/","title":{"rendered":"Collana Multifilo in Perle Ceramica di Caltagirone Radice di Rubino"},"content":{"rendered":"<p>Collana Multifilo in Perle Ceramica di Caltagirone Radice di Rubino<\/p>\n<p>Preziosa collana, multifilo sul davanti, in perle naturali, radice di rubino e 6 mattonelle in ceramica di Caltagirone<\/p>\n<p>La collana \u00e8 lunga 66\/72 cm<\/p>\n<p>Gold-plated 925 silver clasp<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p class=\"isSelectedEnd\"><strong>Collana Multifilo Perle, Ceramica di Caltagirone e Radice di Rubino \u2764\ufe0f\u2728<\/strong><\/p>\n<p class=\"isSelectedEnd\">Una collana preziosa e ricca di fascino, con una raffinata lavorazione multifilo sul davanti che unisce <strong>perle naturali, radice di rubino e 6 mattonelle in autentica ceramica di Caltagirone<\/strong>. \ud83c\udf3a<\/p>\n<p class=\"isSelectedEnd\">Un gioiello dal carattere deciso, dove i colori e le texture si incontrano creando un insieme originale e molto particolare. Perfetta per chi ama indossare la Sicilia con eleganza e personalit\u00e0. \ud83d\udc8e<\/p>\n<p>\ud83d\udccf Lunghezza: 66\/72 cm<br \/>\n\u2728 Gold-plated 925 silver clasp<\/p>","protected":false},"featured_media":52666,"template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[34,43,45,1016],"product_tag":[717,103,361,199,188,351,156,343,71,474,116],"class_list":["post-52658","product","type-product","status-publish","has-post-thumbnail","product_cat-collane","product_cat-collane-collane","product_cat-collane-siciliane","product_cat-novita","product_tag-ceramica","product_tag-ceramica-di-caltagirone","product_tag-collana","product_tag-collana-artigianale","product_tag-collana-fatta-a-mano","product_tag-mattonelle","product_tag-multifilo","product_tag-perla","product_tag-perle","product_tag-radice-di-rubino","product_tag-rubino","product_shipping_class-350-1000g","first","instock","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Collana Multifilo in Perle Ceramica di Caltagirone Radice di Rubino - FiaJewels<\/title>\n<meta name=\"description\" content=\"Collana Multifilo in Perle Ceramica di Caltagirone Radice di Rubino Preziosa collana, multifilo sul davanti, in perle naturali, radice di rubino e 6 mattone\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fiajewels.it\/en\/product\/collana-multifilo-in-perle-ceramica-di-caltagirone-radice-di-rubino\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Collana Multifilo in Perle Ceramica di Caltagirone Radice di Rubino - FiaJewels\" \/>\n<meta property=\"og:description\" content=\"Collana Multifilo in Perle Ceramica di Caltagirone Radice di Rubino Preziosa collana, multifilo sul davanti, in perle naturali, radice di rubino e 6 mattone\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fiajewels.it\/en\/product\/collana-multifilo-in-perle-ceramica-di-caltagirone-radice-di-rubino\/\" \/>\n<meta property=\"og:site_name\" content=\"FiaJewels\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-02T20:25:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fiajewels.it\/wp-content\/uploads\/2026\/09\/COLLANA-MULTIFILO-PERLE-RUBINO-CERAMICA-DI-CALTAGIRONE-ARTIGIANALE-ARGENTO-DORATO-MATTONELLE-SICILIANA.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1023\" \/>\n\t<meta property=\"og:image:height\" content=\"1537\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fiajewels.it\\\/prodotto\\\/collana-multifilo-in-perle-ceramica-di-caltagirone-radice-di-rubino\\\/\",\"url\":\"https:\\\/\\\/fiajewels.it\\\/prodotto\\\/collana-multifilo-in-perle-ceramica-di-caltagirone-radice-di-rubino\\\/\",\"name\":\"Collana Multifilo in Perle Ceramica di Caltagirone Radice di Rubino - FiaJewels\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fiajewels.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fiajewels.it\\\/prodotto\\\/collana-multifilo-in-perle-ceramica-di-caltagirone-radice-di-rubino\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fiajewels.it\\\/prodotto\\\/collana-multifilo-in-perle-ceramica-di-caltagirone-radice-di-rubino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fiajewels.it\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/COLLANA-MULTIFILO-PERLE-RUBINO-CERAMICA-DI-CALTAGIRONE-ARTIGIANALE-ARGENTO-DORATO-MATTONELLE-SICILIANA.png\",\"datePublished\":\"2026-09-02T20:06:18+00:00\",\"dateModified\":\"2026-09-02T20:25:31+00:00\",\"description\":\"Collana Multifilo in Perle Ceramica di Caltagirone Radice di Rubino Preziosa collana, multifilo sul davanti, in perle naturali, radice di rubino e 6 mattone\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fiajewels.it\\\/prodotto\\\/collana-multifilo-in-perle-ceramica-di-caltagirone-radice-di-rubino\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fiajewels.it\\\/prodotto\\\/collana-multifilo-in-perle-ceramica-di-caltagirone-radice-di-rubino\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/fiajewels.it\\\/prodotto\\\/collana-multifilo-in-perle-ceramica-di-caltagirone-radice-di-rubino\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fiajewels.it\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/COLLANA-MULTIFILO-PERLE-RUBINO-CERAMICA-DI-CALTAGIRONE-ARTIGIANALE-ARGENTO-DORATO-MATTONELLE-SICILIANA.png\",\"contentUrl\":\"https:\\\/\\\/fiajewels.it\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/COLLANA-MULTIFILO-PERLE-RUBINO-CERAMICA-DI-CALTAGIRONE-ARTIGIANALE-ARGENTO-DORATO-MATTONELLE-SICILIANA.png\",\"width\":1023,\"height\":1537},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fiajewels.it\\\/prodotto\\\/collana-multifilo-in-perle-ceramica-di-caltagirone-radice-di-rubino\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fiajewels.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/fiajewels.it\\\/negozio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Collana Multifilo in Perle Ceramica di Caltagirone Radice di Rubino\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fiajewels.it\\\/#website\",\"url\":\"https:\\\/\\\/fiajewels.it\\\/\",\"name\":\"FiaJewels\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/fiajewels.it\\\/#\\\/schema\\\/person\\\/85dbc9b8bcf0e0f3481706ec16680240\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fiajewels.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/fiajewels.it\\\/#\\\/schema\\\/person\\\/85dbc9b8bcf0e0f3481706ec16680240\",\"name\":\"FiaJewels\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b9a386afa40b1775488d216d9f973cb34fb853546ac7d5681edead69ac4dfde1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b9a386afa40b1775488d216d9f973cb34fb853546ac7d5681edead69ac4dfde1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b9a386afa40b1775488d216d9f973cb34fb853546ac7d5681edead69ac4dfde1?s=96&d=mm&r=g\",\"caption\":\"FiaJewels\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b9a386afa40b1775488d216d9f973cb34fb853546ac7d5681edead69ac4dfde1?s=96&d=mm&r=g\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Collana Multifilo in Perle Ceramica di Caltagirone Radice di Rubino - FiaJewels","description":"Collana Multifilo in Perle Ceramica di Caltagirone Radice di Rubino Preziosa collana, multifilo sul davanti, in perle naturali, radice di rubino e 6 mattone","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fiajewels.it\/en\/product\/collana-multifilo-in-perle-ceramica-di-caltagirone-radice-di-rubino\/","og_locale":"en_GB","og_type":"article","og_title":"Collana Multifilo in Perle Ceramica di Caltagirone Radice di Rubino - FiaJewels","og_description":"Collana Multifilo in Perle Ceramica di Caltagirone Radice di Rubino Preziosa collana, multifilo sul davanti, in perle naturali, radice di rubino e 6 mattone","og_url":"https:\/\/fiajewels.it\/en\/product\/collana-multifilo-in-perle-ceramica-di-caltagirone-radice-di-rubino\/","og_site_name":"FiaJewels","article_modified_time":"2026-09-02T20:25:31+00:00","og_image":[{"width":1023,"height":1537,"url":"https:\/\/fiajewels.it\/wp-content\/uploads\/2026\/09\/COLLANA-MULTIFILO-PERLE-RUBINO-CERAMICA-DI-CALTAGIRONE-ARTIGIANALE-ARGENTO-DORATO-MATTONELLE-SICILIANA.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fiajewels.it\/prodotto\/collana-multifilo-in-perle-ceramica-di-caltagirone-radice-di-rubino\/","url":"https:\/\/fiajewels.it\/prodotto\/collana-multifilo-in-perle-ceramica-di-caltagirone-radice-di-rubino\/","name":"Collana Multifilo in Perle Ceramica di Caltagirone Radice di Rubino - FiaJewels","isPartOf":{"@id":"https:\/\/fiajewels.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fiajewels.it\/prodotto\/collana-multifilo-in-perle-ceramica-di-caltagirone-radice-di-rubino\/#primaryimage"},"image":{"@id":"https:\/\/fiajewels.it\/prodotto\/collana-multifilo-in-perle-ceramica-di-caltagirone-radice-di-rubino\/#primaryimage"},"thumbnailUrl":"https:\/\/fiajewels.it\/wp-content\/uploads\/2026\/09\/COLLANA-MULTIFILO-PERLE-RUBINO-CERAMICA-DI-CALTAGIRONE-ARTIGIANALE-ARGENTO-DORATO-MATTONELLE-SICILIANA.png","datePublished":"2026-09-02T20:06:18+00:00","dateModified":"2026-09-02T20:25:31+00:00","description":"Collana Multifilo in Perle Ceramica di Caltagirone Radice di Rubino Preziosa collana, multifilo sul davanti, in perle naturali, radice di rubino e 6 mattone","breadcrumb":{"@id":"https:\/\/fiajewels.it\/prodotto\/collana-multifilo-in-perle-ceramica-di-caltagirone-radice-di-rubino\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fiajewels.it\/prodotto\/collana-multifilo-in-perle-ceramica-di-caltagirone-radice-di-rubino\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/fiajewels.it\/prodotto\/collana-multifilo-in-perle-ceramica-di-caltagirone-radice-di-rubino\/#primaryimage","url":"https:\/\/fiajewels.it\/wp-content\/uploads\/2026\/09\/COLLANA-MULTIFILO-PERLE-RUBINO-CERAMICA-DI-CALTAGIRONE-ARTIGIANALE-ARGENTO-DORATO-MATTONELLE-SICILIANA.png","contentUrl":"https:\/\/fiajewels.it\/wp-content\/uploads\/2026\/09\/COLLANA-MULTIFILO-PERLE-RUBINO-CERAMICA-DI-CALTAGIRONE-ARTIGIANALE-ARGENTO-DORATO-MATTONELLE-SICILIANA.png","width":1023,"height":1537},{"@type":"BreadcrumbList","@id":"https:\/\/fiajewels.it\/prodotto\/collana-multifilo-in-perle-ceramica-di-caltagirone-radice-di-rubino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fiajewels.it\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/fiajewels.it\/negozio\/"},{"@type":"ListItem","position":3,"name":"Collana Multifilo in Perle Ceramica di Caltagirone Radice di Rubino"}]},{"@type":"WebSite","@id":"https:\/\/fiajewels.it\/#website","url":"https:\/\/fiajewels.it\/","name":"FiaJewels","description":"","publisher":{"@id":"https:\/\/fiajewels.it\/#\/schema\/person\/85dbc9b8bcf0e0f3481706ec16680240"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fiajewels.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":["Person","Organization"],"@id":"https:\/\/fiajewels.it\/#\/schema\/person\/85dbc9b8bcf0e0f3481706ec16680240","name":"FiaJewels","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/b9a386afa40b1775488d216d9f973cb34fb853546ac7d5681edead69ac4dfde1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b9a386afa40b1775488d216d9f973cb34fb853546ac7d5681edead69ac4dfde1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b9a386afa40b1775488d216d9f973cb34fb853546ac7d5681edead69ac4dfde1?s=96&d=mm&r=g","caption":"FiaJewels"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/b9a386afa40b1775488d216d9f973cb34fb853546ac7d5681edead69ac4dfde1?s=96&d=mm&r=g"}}]}},"_links":{"self":[{"href":"https:\/\/fiajewels.it\/en\/wp-json\/wp\/v2\/product\/52658","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fiajewels.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/fiajewels.it\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fiajewels.it\/en\/wp-json\/wp\/v2\/media\/52666"}],"wp:attachment":[{"href":"https:\/\/fiajewels.it\/en\/wp-json\/wp\/v2\/media?parent=52658"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/fiajewels.it\/en\/wp-json\/wp\/v2\/product_brand?post=52658"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/fiajewels.it\/en\/wp-json\/wp\/v2\/product_cat?post=52658"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/fiajewels.it\/en\/wp-json\/wp\/v2\/product_tag?post=52658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}