{"id":47246,"date":"2026-06-14T00:27:20","date_gmt":"2026-06-13T22:27:20","guid":{"rendered":"https:\/\/fiajewels.it\/?post_type=product&#038;p=47246"},"modified":"2026-08-31T22:07:21","modified_gmt":"2026-08-31T20:07:21","slug":"collana-multifilo-ceramica-di-caltagirone-tormaline-rosa-perla-2","status":"publish","type":"product","link":"https:\/\/fiajewels.it\/en\/product\/collana-multifilo-ceramica-di-caltagirone-tormaline-rosa-perla-2\/","title":{"rendered":"Caltagirone Ceramic Multi-Strand Necklace with Pink Tourmalines and Pearls"},"content":{"rendered":"<p>Caltagirone Ceramic Multi-Strand Necklace with Pink Tourmalines and Pearls<\/p>\n<p>Fabulous necklace<\/p>\n<p>entirely handmade, with a Caltagirone ceramic plate, finely hand-decorated with pure gold and many antique pink tourmaline pendants and a baroque pearl on the side<\/p>\n<p>The chains are made of 7-layer 24kt gold plated brass<\/p>\n<p>The necklace consists of two strands at the front and one at the back. The length of the two strands is 76 cm and 84 cm.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p data-start=\"165\" data-end=\"240\"><strong data-start=\"165\" data-end=\"240\">Caltagirone Ceramic Multi-Strand Necklace with Tourmalines and Pearls\u00a0<\/strong><\/p>\n<p data-start=\"165\" data-end=\"240\">\u201cThe Women\u201d<\/p>\n<p>Caltagirone Ceramic Multi-Strand Necklace with Pink Tourmalines and Pearls<\/p>\n<p>Fabulous necklace<\/p>\n<p>entirely handmade, with a Caltagirone ceramic plate, finely hand-decorated with pure gold and many antique pink tourmaline pendants and a baroque pearl on the side<\/p>\n<p>The chains are made of 7-layer 24kt gold plated brass<\/p>\n<p>The necklace is made up of two strands on the front and one on the back. The length of the two strands is 76 and 84 cm and it does not have a clasp.<\/p>\n<p>&nbsp;<\/p>","protected":false},"featured_media":47252,"template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[34,43,45],"product_tag":[1626,103,202,206,187,212,213,98,214,343,71,211,215,669],"class_list":["post-47246","product","type-product","status-publish","has-post-thumbnail","product_cat-collane","product_cat-collane-collane","product_cat-collane-siciliane","product_tag-barocca","product_tag-ceramica-di-caltagirone","product_tag-collana-in-ceramica","product_tag-collana-per-regalo","product_tag-collana-siciliana","product_tag-collane-artigianali","product_tag-collane-siciliane","product_tag-gioielli-artigianali","product_tag-gioielli-siciliani","product_tag-perla","product_tag-perle","product_tag-sicilia","product_tag-stile-siciliano","product_tag-tormaline","product_shipping_class-350-1000g","first","instock","sale","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Collana Multifilo Ceramica di Caltagirone Tormaline Rosa Perla - FiaJewels<\/title>\n<meta name=\"description\" content=\"Collana Multifilo Ceramica di Caltagirone Tormaline Rosa Perla Collana favolosafatta interamente a mano, con piastra in ceramica di Caltagirone\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fiajewels.it\/en\/product\/collana-multifilo-ceramica-di-caltagirone-tormaline-rosa-perla-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Collana Multifilo Ceramica di Caltagirone Tormaline Rosa Perla - FiaJewels\" \/>\n<meta property=\"og:description\" content=\"Collana Multifilo Ceramica di Caltagirone Tormaline Rosa Perla Collana favolosafatta interamente a mano, con piastra in ceramica di Caltagirone\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fiajewels.it\/en\/product\/collana-multifilo-ceramica-di-caltagirone-tormaline-rosa-perla-2\/\" \/>\n<meta property=\"og:site_name\" content=\"FiaJewels\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-31T20:07:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fiajewels.it\/wp-content\/uploads\/2026\/06\/COLLANA-MULTIFILO-PIASTRA-CERAMICA-DI-CALTAGIRONE-TORMALINE-ROSA-5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2496\" \/>\n\t<meta property=\"og:image:height\" content=\"1664\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fiajewels.it\\\/prodotto\\\/collana-multifilo-ceramica-di-caltagirone-tormaline-rosa-perla-2\\\/\",\"url\":\"https:\\\/\\\/fiajewels.it\\\/prodotto\\\/collana-multifilo-ceramica-di-caltagirone-tormaline-rosa-perla-2\\\/\",\"name\":\"Collana Multifilo Ceramica di Caltagirone Tormaline Rosa Perla - FiaJewels\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fiajewels.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fiajewels.it\\\/prodotto\\\/collana-multifilo-ceramica-di-caltagirone-tormaline-rosa-perla-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fiajewels.it\\\/prodotto\\\/collana-multifilo-ceramica-di-caltagirone-tormaline-rosa-perla-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fiajewels.it\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/COLLANA-MULTIFILO-PIASTRA-CERAMICA-DI-CALTAGIRONE-TORMALINE-ROSA-5.jpg\",\"datePublished\":\"2026-06-13T22:27:20+00:00\",\"dateModified\":\"2026-08-31T20:07:21+00:00\",\"description\":\"Collana Multifilo Ceramica di Caltagirone Tormaline Rosa Perla Collana favolosafatta interamente a mano, con piastra in ceramica di Caltagirone\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fiajewels.it\\\/prodotto\\\/collana-multifilo-ceramica-di-caltagirone-tormaline-rosa-perla-2\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fiajewels.it\\\/prodotto\\\/collana-multifilo-ceramica-di-caltagirone-tormaline-rosa-perla-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/fiajewels.it\\\/prodotto\\\/collana-multifilo-ceramica-di-caltagirone-tormaline-rosa-perla-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fiajewels.it\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/COLLANA-MULTIFILO-PIASTRA-CERAMICA-DI-CALTAGIRONE-TORMALINE-ROSA-5.jpg\",\"contentUrl\":\"https:\\\/\\\/fiajewels.it\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/COLLANA-MULTIFILO-PIASTRA-CERAMICA-DI-CALTAGIRONE-TORMALINE-ROSA-5.jpg\",\"width\":2496,\"height\":1664},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fiajewels.it\\\/prodotto\\\/collana-multifilo-ceramica-di-caltagirone-tormaline-rosa-perla-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fiajewels.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/fiajewels.it\\\/negozio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Collana Multifilo Ceramica di Caltagirone Tormaline Rosa Perla\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fiajewels.it\\\/#website\",\"url\":\"https:\\\/\\\/fiajewels.it\\\/\",\"name\":\"FiaJewels\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/fiajewels.it\\\/#\\\/schema\\\/person\\\/85dbc9b8bcf0e0f3481706ec16680240\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fiajewels.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/fiajewels.it\\\/#\\\/schema\\\/person\\\/85dbc9b8bcf0e0f3481706ec16680240\",\"name\":\"FiaJewels\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b9a386afa40b1775488d216d9f973cb34fb853546ac7d5681edead69ac4dfde1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b9a386afa40b1775488d216d9f973cb34fb853546ac7d5681edead69ac4dfde1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b9a386afa40b1775488d216d9f973cb34fb853546ac7d5681edead69ac4dfde1?s=96&d=mm&r=g\",\"caption\":\"FiaJewels\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b9a386afa40b1775488d216d9f973cb34fb853546ac7d5681edead69ac4dfde1?s=96&d=mm&r=g\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Collana Multifilo Ceramica di Caltagirone Tormaline Rosa Perla - FiaJewels","description":"Collana Multifilo Ceramica di Caltagirone Tormaline Rosa Perla Collana favolosafatta interamente a mano, con piastra in ceramica di Caltagirone","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fiajewels.it\/en\/product\/collana-multifilo-ceramica-di-caltagirone-tormaline-rosa-perla-2\/","og_locale":"en_GB","og_type":"article","og_title":"Collana Multifilo Ceramica di Caltagirone Tormaline Rosa Perla - FiaJewels","og_description":"Collana Multifilo Ceramica di Caltagirone Tormaline Rosa Perla Collana favolosafatta interamente a mano, con piastra in ceramica di Caltagirone","og_url":"https:\/\/fiajewels.it\/en\/product\/collana-multifilo-ceramica-di-caltagirone-tormaline-rosa-perla-2\/","og_site_name":"FiaJewels","article_modified_time":"2026-08-31T20:07:21+00:00","og_image":[{"width":2496,"height":1664,"url":"https:\/\/fiajewels.it\/wp-content\/uploads\/2026\/06\/COLLANA-MULTIFILO-PIASTRA-CERAMICA-DI-CALTAGIRONE-TORMALINE-ROSA-5.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fiajewels.it\/prodotto\/collana-multifilo-ceramica-di-caltagirone-tormaline-rosa-perla-2\/","url":"https:\/\/fiajewels.it\/prodotto\/collana-multifilo-ceramica-di-caltagirone-tormaline-rosa-perla-2\/","name":"Collana Multifilo Ceramica di Caltagirone Tormaline Rosa Perla - FiaJewels","isPartOf":{"@id":"https:\/\/fiajewels.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fiajewels.it\/prodotto\/collana-multifilo-ceramica-di-caltagirone-tormaline-rosa-perla-2\/#primaryimage"},"image":{"@id":"https:\/\/fiajewels.it\/prodotto\/collana-multifilo-ceramica-di-caltagirone-tormaline-rosa-perla-2\/#primaryimage"},"thumbnailUrl":"https:\/\/fiajewels.it\/wp-content\/uploads\/2026\/06\/COLLANA-MULTIFILO-PIASTRA-CERAMICA-DI-CALTAGIRONE-TORMALINE-ROSA-5.jpg","datePublished":"2026-06-13T22:27:20+00:00","dateModified":"2026-08-31T20:07:21+00:00","description":"Collana Multifilo Ceramica di Caltagirone Tormaline Rosa Perla Collana favolosafatta interamente a mano, con piastra in ceramica di Caltagirone","breadcrumb":{"@id":"https:\/\/fiajewels.it\/prodotto\/collana-multifilo-ceramica-di-caltagirone-tormaline-rosa-perla-2\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fiajewels.it\/prodotto\/collana-multifilo-ceramica-di-caltagirone-tormaline-rosa-perla-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/fiajewels.it\/prodotto\/collana-multifilo-ceramica-di-caltagirone-tormaline-rosa-perla-2\/#primaryimage","url":"https:\/\/fiajewels.it\/wp-content\/uploads\/2026\/06\/COLLANA-MULTIFILO-PIASTRA-CERAMICA-DI-CALTAGIRONE-TORMALINE-ROSA-5.jpg","contentUrl":"https:\/\/fiajewels.it\/wp-content\/uploads\/2026\/06\/COLLANA-MULTIFILO-PIASTRA-CERAMICA-DI-CALTAGIRONE-TORMALINE-ROSA-5.jpg","width":2496,"height":1664},{"@type":"BreadcrumbList","@id":"https:\/\/fiajewels.it\/prodotto\/collana-multifilo-ceramica-di-caltagirone-tormaline-rosa-perla-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fiajewels.it\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/fiajewels.it\/negozio\/"},{"@type":"ListItem","position":3,"name":"Collana Multifilo Ceramica di Caltagirone Tormaline Rosa Perla"}]},{"@type":"WebSite","@id":"https:\/\/fiajewels.it\/#website","url":"https:\/\/fiajewels.it\/","name":"FiaJewels","description":"","publisher":{"@id":"https:\/\/fiajewels.it\/#\/schema\/person\/85dbc9b8bcf0e0f3481706ec16680240"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fiajewels.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":["Person","Organization"],"@id":"https:\/\/fiajewels.it\/#\/schema\/person\/85dbc9b8bcf0e0f3481706ec16680240","name":"FiaJewels","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/b9a386afa40b1775488d216d9f973cb34fb853546ac7d5681edead69ac4dfde1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b9a386afa40b1775488d216d9f973cb34fb853546ac7d5681edead69ac4dfde1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b9a386afa40b1775488d216d9f973cb34fb853546ac7d5681edead69ac4dfde1?s=96&d=mm&r=g","caption":"FiaJewels"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/b9a386afa40b1775488d216d9f973cb34fb853546ac7d5681edead69ac4dfde1?s=96&d=mm&r=g"}}]}},"_links":{"self":[{"href":"https:\/\/fiajewels.it\/en\/wp-json\/wp\/v2\/product\/47246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fiajewels.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/fiajewels.it\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fiajewels.it\/en\/wp-json\/wp\/v2\/media\/47252"}],"wp:attachment":[{"href":"https:\/\/fiajewels.it\/en\/wp-json\/wp\/v2\/media?parent=47246"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/fiajewels.it\/en\/wp-json\/wp\/v2\/product_brand?post=47246"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/fiajewels.it\/en\/wp-json\/wp\/v2\/product_cat?post=47246"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/fiajewels.it\/en\/wp-json\/wp\/v2\/product_tag?post=47246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}